{"id":753,"count":1,"description":"","link":"https:\/\/filmoskopija.com\/en\/tag\/urska-djukic\/","name":"ur\u0161ka djuki\u0107","slug":"urska-djukic","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ur\u0161ka djuki\u0107 Archives - Filmoskopija<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filmoskopija.com\/en\/tag\/urska-djukic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ur\u0161ka djuki\u0107 Archives - Filmoskopija\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filmoskopija.com\/en\/tag\/urska-djukic\/\" \/>\n<meta property=\"og:site_name\" content=\"Filmoskopija\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/filmoskopija.com\/tag\/urska-djukic\/\",\"url\":\"https:\/\/filmoskopija.com\/tag\/urska-djukic\/\",\"name\":\"ur\u0161ka djuki\u0107 Archives - Filmoskopija\",\"isPartOf\":{\"@id\":\"https:\/\/filmoskopija.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/filmoskopija.com\/tag\/urska-djukic\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/filmoskopija.com\/tag\/urska-djukic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/filmoskopija.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ur\u0161ka djuki\u0107\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/filmoskopija.com\/#website\",\"url\":\"https:\/\/filmoskopija.com\/\",\"name\":\"Filmoskopija\",\"description\":\"Filmske kritike, eseji, intervjui i vesti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/filmoskopija.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ur\u0161ka djuki\u0107 Archives - Filmoskopija","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filmoskopija.com\/en\/tag\/urska-djukic\/","og_locale":"en_US","og_type":"article","og_title":"ur\u0161ka djuki\u0107 Archives - Filmoskopija","og_url":"https:\/\/filmoskopija.com\/en\/tag\/urska-djukic\/","og_site_name":"Filmoskopija","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/filmoskopija.com\/tag\/urska-djukic\/","url":"https:\/\/filmoskopija.com\/tag\/urska-djukic\/","name":"ur\u0161ka djuki\u0107 Archives - Filmoskopija","isPartOf":{"@id":"https:\/\/filmoskopija.com\/#website"},"breadcrumb":{"@id":"https:\/\/filmoskopija.com\/tag\/urska-djukic\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/filmoskopija.com\/tag\/urska-djukic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/filmoskopija.com\/"},{"@type":"ListItem","position":2,"name":"ur\u0161ka djuki\u0107"}]},{"@type":"WebSite","@id":"https:\/\/filmoskopija.com\/#website","url":"https:\/\/filmoskopija.com\/","name":"Filmoskopija","description":"Filmske kritike, eseji, intervjui i vesti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filmoskopija.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/filmoskopija.com\/en\/wp-json\/wp\/v2\/tags\/753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filmoskopija.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/filmoskopija.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/filmoskopija.com\/en\/wp-json\/wp\/v2\/posts?tags=753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}